{"id":4737,"date":"2024-11-28T13:05:05","date_gmt":"2024-11-28T13:05:05","guid":{"rendered":"https:\/\/demoscan.ch\/?post_type=delib-prozesse&#038;p=4737"},"modified":"2026-03-08T11:38:15","modified_gmt":"2026-03-08T11:38:15","slug":"bevoelkerungsrat-2025","status":"publish","type":"delib-prozesse","link":"https:\/\/demoscan.ch\/fr\/delib-prozesse\/bevoelkerungsrat-2025\/","title":{"rendered":"Bev\u00f6lkerungsrat 2025"},"excerpt":{"rendered":"<p>Auf nationaler Ebene erarbeitete ein Bev\u00f6lkerungsrat Reformvorschl\u00e4ge zur Eind\u00e4mmung steigender Gesundheitskosten mit Schwerpunkt auf Gesundheitsf\u00f6rderung und Pr\u00e4vention.<\/p>","protected":false},"featured_media":5467,"template":"","class_list":["post-4737","delib-prozesse","type-delib-prozesse","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/demoscan.ch\/fr\/wp-json\/wp\/v2\/delib-prozesse\/4737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demoscan.ch\/fr\/wp-json\/wp\/v2\/delib-prozesse"}],"about":[{"href":"https:\/\/demoscan.ch\/fr\/wp-json\/wp\/v2\/types\/delib-prozesse"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/demoscan.ch\/fr\/wp-json\/wp\/v2\/media\/5467"}],"wp:attachment":[{"href":"https:\/\/demoscan.ch\/fr\/wp-json\/wp\/v2\/media?parent=4737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}