{"id":4665,"date":"2022-04-27T10:02:03","date_gmt":"2022-04-27T10:02:03","guid":{"rendered":"https:\/\/demoscan.ch\/?post_type=delib-prozesse&#038;p=4665"},"modified":"2026-03-08T11:28:19","modified_gmt":"2026-03-08T11:28:19","slug":"conseil-citoyen-yverdon","status":"publish","type":"delib-prozesse","link":"https:\/\/demoscan.ch\/fr\/delib-prozesse\/conseil-citoyen-yverdon\/","title":{"rendered":"Conseil Citoyen Yverdon"},"excerpt":{"rendered":"<p>In der Stadt Yverdon erarbeitete ein B\u00fcrgerrat Vorschl\u00e4ge f\u00fcr Klimaschutzmassnahmen im Rahmen der Ausarbeitung des kommunalen Klimaschutzplans.<\/p>","protected":false},"featured_media":4980,"template":"","class_list":["post-4665","delib-prozesse","type-delib-prozesse","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/demoscan.ch\/fr\/wp-json\/wp\/v2\/delib-prozesse\/4665","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/demoscan.ch\/fr\/wp-json\/wp\/v2\/delib-prozesse"}],"about":[{"href":"https:\/\/demoscan.ch\/fr\/wp-json\/wp\/v2\/types\/delib-prozesse"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/demoscan.ch\/fr\/wp-json\/wp\/v2\/media\/4980"}],"wp:attachment":[{"href":"https:\/\/demoscan.ch\/fr\/wp-json\/wp\/v2\/media?parent=4665"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}